{"id":270,"count":98,"description":"","link":"https:\/\/ieltsnpte.com\/updates\/category\/admission-visa-process\/","name":"Admission &amp; Visa Process","slug":"admission-visa-process","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/ieltsnpte.com\/updates\/wp-json\/wp\/v2\/categories\/270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ieltsnpte.com\/updates\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/ieltsnpte.com\/updates\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/ieltsnpte.com\/updates\/wp-json\/wp\/v2\/posts?categories=270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}